{"id":9004111222137473,"date":"2022-12-14T14:33:38","date_gmt":"2022-12-14T14:33:38","guid":{"rendered":"https:\/\/www.hgf.com\/?p=9004111222137473"},"modified":"2025-11-13T20:10:23","modified_gmt":"2025-11-13T20:10:23","slug":"les-mesures-transitoires-du-brevet-unitaire","status":"publish","type":"post","link":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/","title":{"rendered":"Les mesures transitoires du brevet unitaire"},"content":{"rendered":"<p>Lorsque la Juridiction unifi\u00e9e du brevet (JUB) entrera finalement en vigueur (actuellement <a href=\"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/debut-de-la-periode-de-transition-de-la-jub-reporte-au-1er-mars-2023\/\">report\u00e9e au 1er juin 2023<\/a>), il sera possible d&#8217;obtenir une protection par brevet dans les \u00c9tats membres de la JUB en demandant une protection unitaire sous forme de brevet unitaire (BU).<\/p>\n<p>Afin de soutenir les utilisateurs dans l&#8217;adoption pr\u00e9coce du BU, l&#8217;OEB met en place deux mesures transitoires avant l&#8217;entr\u00e9e en vigueur de la JUB. Les informations relatives \u00e0 ces deux mesures transitoires sont disponibles <g id=\"gid_0\">ici<\/g>. Ces mesures sont :  <\/p>\n<ul>\n<li>Demande anticip\u00e9e d&#8217;effet unitaire<\/li>\n<li>Demande de report de la d\u00e9cision de d\u00e9livrance d&#8217;un brevet europ\u00e9en<\/li>\n<\/ul>\n<p>Malgr\u00e9 le report de la <a href=\"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/debut-de-la-periode-de-transition-de-la-jub-reporte-au-1er-mars-2023\/\">date d&#8217;entr\u00e9e en vigueur de la JUB<\/a>, l&#8217;OEB a confirm\u00e9 son intention de mettre en \u0153uvre ses mesures transitoires \u00e0 partir du 1er janvier 2023 comme pr\u00e9vu initialement.<\/p>\n<p>Ces mesures transitoires relatives au BU se poursuivront jusqu&#8217;\u00e0 l&#8217;entr\u00e9e en vigueur de la JUB. Si cette date est ult\u00e9rieure, les mesures transitoires de l&#8217;OEB seront prolong\u00e9es en cons\u00e9quence. <\/p>\n<p><strong>Devrais-je envisager d&#8217;utiliser une ou les deux mesures transitoires de l&#8217;OEB concernant le BU ?<\/strong><\/p>\n<p>En raison de la p\u00e9riode transitoire prolong\u00e9e, <strong>actuellement, la seule fa\u00e7on fiable d&#8217;obtenir un BU est de demander \u00e0 l&#8217;OEB de reporter la d\u00e9cision de d\u00e9livrance d&#8217;un brevet europ\u00e9en<\/strong>. En effet, un BU ne peut \u00eatre demand\u00e9 que pour tout brevet europ\u00e9en d\u00e9livr\u00e9 \u00e0 la date d&#8217;entr\u00e9e en vigueur de l&#8217;accord JUB ou apr\u00e8s celle-ci (pr\u00e9vue pour le 1er juin 2023). La demande de report de la d\u00e9cision de d\u00e9livrance garantira que la mention de la d\u00e9livrance du brevet europ\u00e9en sera publi\u00e9e dans le Bulletin europ\u00e9en des brevets \u00e0 la date d&#8217;entr\u00e9e en vigueur de la JUB ou imm\u00e9diatement apr\u00e8s, rendant ainsi un brevet europ\u00e9en (qui aurait autrement \u00e9t\u00e9 d\u00e9livr\u00e9 avant le d\u00e9but de la JUB) \u00e9ligible \u00e0 la protection par brevet unitaire.  <\/p>\n<p>Concr\u00e8tement, cela signifie que les demandeurs peuvent chercher \u00e0 reporter la d\u00e9livrance de leur brevet europ\u00e9en \u00e0 partir du 1er janvier 2023, lorsqu&#8217;ils ont re\u00e7u le texte destin\u00e9 \u00e0 la d\u00e9livrance, mais ne l&#8217;ont pas encore approuv\u00e9. Une demande de report d\u00e9pos\u00e9e le m\u00eame jour que l&#8217;approbation du texte destin\u00e9 \u00e0 la d\u00e9livrance sera consid\u00e9r\u00e9e comme valablement d\u00e9pos\u00e9e. Un BU pourra alors \u00eatre demand\u00e9 ult\u00e9rieurement (selon le d\u00e9lai applicable).  <\/p>\n<p><strong>Le risque associ\u00e9 \u00e0 l&#8217;autre mesure transitoire (la demande anticip\u00e9e d&#8217;effet unitaire) est que l&#8217;OEB continuera \u00e0 \u00e9mettre sa d\u00e9cision de d\u00e9livrance ind\u00e9pendamment du d\u00e9p\u00f4t de la demande anticip\u00e9e d&#8217;effet unitaire et, si la mention de la d\u00e9livrance du brevet europ\u00e9en est publi\u00e9e dans le Bulletin europ\u00e9en des brevets avant le 1er juin 2023, la demande d&#8217;effet unitaire ne sera pas valablement d\u00e9pos\u00e9e. Le demandeur aura alors perdu la possibilit\u00e9 d&#8217;obtenir une protection via le BU (puisque l&#8217;autre mesure transitoire ne serait plus disponible). <\/strong><\/p>\n<p><strong>Recommandations :<\/strong><\/p>\n<p>Si la priorit\u00e9 du demandeur est d&#8217;obtenir une protection BU plut\u00f4t qu&#8217;une protection par brevet rapide, notre recommandation est de demander un report de la d\u00e9cision de d\u00e9livrance du brevet europ\u00e9en. Toutefois, l&#8217;inconv\u00e9nient de cette demande de report est que la d\u00e9livrance dans les pays non-BU sera \u00e9galement retard\u00e9e. <\/p>\n<p>Si la priorit\u00e9 du demandeur est d&#8217;obtenir une protection par brevet le plus t\u00f4t possible et s&#8217;il est dispos\u00e9 \u00e0 valider sur une base nationale de mani\u00e8re traditionnelle comme solution de repli (en raison du report de la JUB et\/ou si l&#8217;OEB \u00e9met la d\u00e9cision de d\u00e9livrance plus t\u00f4t que pr\u00e9vu), notre recommandation est de r\u00e9pondre \u00e0 la notification selon la r\u00e8gle 71(3) le plus pr\u00e8s possible de la date de d\u00e9but de la JUB et de d\u00e9poser \u00e9galement une demande anticip\u00e9e d&#8217;effet unitaire. Cela pourrait n\u00e9anmoins signifier que la mention de la d\u00e9livrance du brevet europ\u00e9en soit publi\u00e9e dans le Bulletin europ\u00e9en des brevets AVANT la date d&#8217;entr\u00e9e en vigueur de la JUB, rendant impossible l&#8217;obtention d&#8217;un BU. <\/p>\n<p>Cet article a \u00e9t\u00e9 pr\u00e9par\u00e9 par <a href=\"https:\/\/www.hgf.com\/fr\/our-people\/andrew-camenisch\/\">Andy Camenisch<\/a>, Associ\u00e9 chez HGF<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lorsque la Juridiction unifi\u00e9e du brevet (JUB) entrera finalement en vigueur (actuellement report\u00e9e au 1er juin 2023), il sera possible d&#8217;obtenir une protection par brevet dans les \u00c9tats membres de &hellip;<\/p>\n","protected":false},"author":316,"featured_media":9004111222135710,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[548,517],"tags":[],"class_list":["post-9004111222137473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites-juridiques","category-centre-de-connaissances"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les mesures transitoires du brevet unitaire - HGF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les mesures transitoires du brevet unitaire\" \/>\n<meta property=\"og:description\" content=\"Lorsque la Juridiction unifi\u00e9e du brevet (JUB) entrera finalement en vigueur (actuellement report\u00e9e au 1er juin 2023), il sera possible d&#039;obtenir une\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/\" \/>\n<meta property=\"og:site_name\" content=\"HGF\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-14T14:33:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T20:10:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hgf.com\/wp-content\/uploads\/2021\/12\/Article-5-UPC-image.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nichola Butler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hgf_ip\" \/>\n<meta name=\"twitter:site\" content=\"@hgf_ip\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nichola Butler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/actualites-juridiques\\\/les-mesures-transitoires-du-brevet-unitaire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/actualites-juridiques\\\/les-mesures-transitoires-du-brevet-unitaire\\\/\"},\"author\":{\"name\":\"Nichola Butler\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#\\\/schema\\\/person\\\/b8e8f97c9bef17c5a63b58710dec05fc\"},\"headline\":\"Les mesures transitoires du brevet unitaire\",\"datePublished\":\"2022-12-14T14:33:38+00:00\",\"dateModified\":\"2025-11-13T20:10:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/actualites-juridiques\\\/les-mesures-transitoires-du-brevet-unitaire\\\/\"},\"wordCount\":744,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/actualites-juridiques\\\/les-mesures-transitoires-du-brevet-unitaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Article-5-UPC-image.jpg\",\"articleSection\":[\"Actualit\u00e9s juridiques\",\"Centre de connaissances\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/actualites-juridiques\\\/les-mesures-transitoires-du-brevet-unitaire\\\/\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/actualites-juridiques\\\/les-mesures-transitoires-du-brevet-unitaire\\\/\",\"name\":\"Les mesures transitoires du brevet unitaire - HGF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/actualites-juridiques\\\/les-mesures-transitoires-du-brevet-unitaire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/actualites-juridiques\\\/les-mesures-transitoires-du-brevet-unitaire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Article-5-UPC-image.jpg\",\"datePublished\":\"2022-12-14T14:33:38+00:00\",\"dateModified\":\"2025-11-13T20:10:23+00:00\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/actualites-juridiques\\\/les-mesures-transitoires-du-brevet-unitaire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/actualites-juridiques\\\/les-mesures-transitoires-du-brevet-unitaire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Article-5-UPC-image.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/Article-5-UPC-image.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/\",\"name\":\"HGF\",\"description\":\"Intellectual Property Rights specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#organization\",\"name\":\"HGF\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hgf-logo-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hgf-logo-696x696-1.png\",\"width\":696,\"height\":696,\"caption\":\"HGF\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/hgf_ip\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hgf-limited-intellectual-property-specialists\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#\\\/schema\\\/person\\\/b8e8f97c9bef17c5a63b58710dec05fc\",\"name\":\"Nichola Butler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g\",\"caption\":\"Nichola Butler\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les mesures transitoires du brevet unitaire - HGF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/","og_locale":"fr_FR","og_type":"article","og_title":"Les mesures transitoires du brevet unitaire","og_description":"Lorsque la Juridiction unifi\u00e9e du brevet (JUB) entrera finalement en vigueur (actuellement report\u00e9e au 1er juin 2023), il sera possible d'obtenir une","og_url":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/","og_site_name":"HGF","article_published_time":"2022-12-14T14:33:38+00:00","article_modified_time":"2025-11-13T20:10:23+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2021\/12\/Article-5-UPC-image.jpg","type":"image\/jpeg"}],"author":"Nichola Butler","twitter_card":"summary_large_image","twitter_creator":"@hgf_ip","twitter_site":"@hgf_ip","twitter_misc":{"\u00c9crit par":"Nichola Butler","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/#article","isPartOf":{"@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/"},"author":{"name":"Nichola Butler","@id":"https:\/\/www.hgf.com\/fr\/#\/schema\/person\/b8e8f97c9bef17c5a63b58710dec05fc"},"headline":"Les mesures transitoires du brevet unitaire","datePublished":"2022-12-14T14:33:38+00:00","dateModified":"2025-11-13T20:10:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/"},"wordCount":744,"publisher":{"@id":"https:\/\/www.hgf.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2021\/12\/Article-5-UPC-image.jpg","articleSection":["Actualit\u00e9s juridiques","Centre de connaissances"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/","url":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/","name":"Les mesures transitoires du brevet unitaire - HGF","isPartOf":{"@id":"https:\/\/www.hgf.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/#primaryimage"},"image":{"@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2021\/12\/Article-5-UPC-image.jpg","datePublished":"2022-12-14T14:33:38+00:00","dateModified":"2025-11-13T20:10:23+00:00","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/actualites-juridiques\/les-mesures-transitoires-du-brevet-unitaire\/#primaryimage","url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2021\/12\/Article-5-UPC-image.jpg","contentUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2021\/12\/Article-5-UPC-image.jpg","width":1920,"height":1080},{"@type":"WebSite","@id":"https:\/\/www.hgf.com\/fr\/#website","url":"https:\/\/www.hgf.com\/fr\/","name":"HGF","description":"Intellectual Property Rights specialists","publisher":{"@id":"https:\/\/www.hgf.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hgf.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.hgf.com\/fr\/#organization","name":"HGF","url":"https:\/\/www.hgf.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hgf.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/04\/hgf-logo-696x696-1.png","contentUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/04\/hgf-logo-696x696-1.png","width":696,"height":696,"caption":"HGF"},"image":{"@id":"https:\/\/www.hgf.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/hgf_ip","https:\/\/www.linkedin.com\/company\/hgf-limited-intellectual-property-specialists\/"]},{"@type":"Person","@id":"https:\/\/www.hgf.com\/fr\/#\/schema\/person\/b8e8f97c9bef17c5a63b58710dec05fc","name":"Nichola Butler","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g","caption":"Nichola Butler"}}]}},"_links":{"self":[{"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/posts\/9004111222137473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/users\/316"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/comments?post=9004111222137473"}],"version-history":[{"count":0,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/posts\/9004111222137473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/media\/9004111222135710"}],"wp:attachment":[{"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/media?parent=9004111222137473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/categories?post=9004111222137473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/tags?post=9004111222137473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}