{"id":9004111222136954,"date":"2024-03-12T13:33:59","date_gmt":"2024-03-12T13:33:59","guid":{"rendered":"https:\/\/www.hgf.com\/?p=9004111222136954"},"modified":"2025-11-13T20:08:53","modified_gmt":"2025-11-13T20:08:53","slug":"inequitable-un-regard-sur-les-jugements-thatchers-et-lidl","status":"publish","type":"post","link":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/","title":{"rendered":"[in]\u00e9quitable \u2013 un regard sur les jugements Thatchers et Lidl"},"content":{"rendered":"<p class=\"p__large\"><em>Nous examinons l&#8217;avantage d\u00e9loyal et le pr\u00e9judice \u00e0 travers le prisme des r\u00e9cents jugements Lidl c. Tesco et Thatchers c. Aldi. Deux r\u00e9sultats tr\u00e8s diff\u00e9rents sur les m\u00eames principes juridiques et peut-\u00eatre un point de controverse en appel. <\/em><\/p>\n<h5>Les litiges<\/h5>\n<p>Dans <strong>Thatchers c. Aldi<\/strong>, le litige porte sur l&#8217;apparence g\u00e9n\u00e9rale du THATCHERS CLOUDY LEMON CIDER &#8211; pour lequel Thatchers d\u00e9tient un enregistrement de marque pour la marque figurative pr\u00e9sent\u00e9e ci-dessous &#8211; et le produit TAURUS CLOUDY LEMON CIDER d&#8217;Aldi (\u00e9galement pr\u00e9sent\u00e9 ci-dessous).<\/p>\n<p>Thatchers a affirm\u00e9 qu&#8217;Aldi avait intentionnellement cherch\u00e9 \u00e0 associer sa propre marque de cidre au produit de Thatchers, tirant un avantage d\u00e9loyal de la r\u00e9putation de la marque Thatchers. Thatchers a \u00e9galement introduit une demande suppl\u00e9mentaire de concurrence d\u00e9loyale. <\/p>\n<p>Le tribunal a conclu que la marque de Thatchers jouissait d&#8217;une r\u00e9putation au Royaume-Uni et que le produit d&#8217;Aldi \u00e9voquerait la marque, mais qu&#8217;il n&#8217;y avait aucun avantage d\u00e9loyal ou pr\u00e9judice \u00e0 la r\u00e9putation de la marque. La demande de concurrence d\u00e9loyale a \u00e9galement \u00e9chou\u00e9 car il n&#8217;y avait pas non plus de fausse d\u00e9claration de la part d&#8217;Aldi. Nous n&#8217;avons pas connaissance d&#8217;un appel \u00e0 ce jour.  <\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-9004111222129986 size-medium\" src=\"https:\/\/img.hgf.com\/spio\/ret_img,q_cdnize,to_auto,s_webp:avif\/www.hgf.com\/wp-content\/uploads\/2024\/03\/Picture7-200x300.jpg\" alt=\"\" width=\"200\" height=\"300\" srcset=\"https:\/\/img.hgf.com\/spio\/ret_img,q_cdnize,to_auto,s_webp:avif\/www.hgf.com\/wp-content\/uploads\/2024\/03\/Picture7-200x300.jpg 200w, https:\/\/img.hgf.com\/spio\/ret_img,q_cdnize,to_auto,s_webp:avif\/www.hgf.com\/wp-content\/uploads\/2024\/03\/Picture7.jpg 284w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><img decoding=\"async\" class=\"alignnone size-medium wp-image-9004111222129988\" src=\"https:\/\/img.hgf.com\/spio\/ret_img,q_cdnize,to_auto,s_webp:avif\/www.hgf.com\/wp-content\/uploads\/2024\/03\/Picture8-241x300.jpg\" alt=\"\" width=\"241\" height=\"300\" srcset=\"https:\/\/img.hgf.com\/spio\/ret_img,q_cdnize,to_auto,s_webp:avif\/www.hgf.com\/wp-content\/uploads\/2024\/03\/Picture8-241x300.jpg 241w, https:\/\/img.hgf.com\/spio\/ret_img,q_cdnize,to_auto,s_webp:avif\/www.hgf.com\/wp-content\/uploads\/2024\/03\/Picture8.jpg 332w\" sizes=\"(max-width: 241px) 100vw, 241px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone size-full wp-image-9004111222129990\" src=\"https:\/\/img.hgf.com\/spio\/ret_img,q_cdnize,to_auto,s_webp:avif\/www.hgf.com\/wp-content\/uploads\/2024\/03\/Picture9.png\" alt=\"\" width=\"125\" height=\"113\"><img decoding=\"async\" class=\"alignnone size-full wp-image-9004111222129992\" src=\"https:\/\/img.hgf.com\/spio\/ret_img,q_cdnize,to_auto,s_webp:avif\/www.hgf.com\/wp-content\/uploads\/2024\/03\/Picture10.png\" alt=\"\" width=\"123\" height=\"111\"><img decoding=\"async\" class=\"alignnone wp-image-9004111222129994\" src=\"https:\/\/www.hgf.com\/wp-content\/uploads\/2024\/03\/Picture11.jpg\" alt=\"\" width=\"110\" height=\"112\" srcset=\"https:\/\/www.hgf.com\/wp-content\/uploads\/2024\/03\/Picture11.jpg 266w, https:\/\/www.hgf.com\/wp-content\/uploads\/2024\/03\/Picture11-70x70.jpg 70w\" sizes=\"(max-width: 110px) 100vw, 110px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Lidl c. Tesco \u00ab tourne autour \u00bb du logo de Lidl et de la marque sans mot ainsi que du dispositif de cercle jaune sur fond bleu, utilis\u00e9 par Tesco pour son programme de fid\u00e9lit\u00e9 \u00e0 prix r\u00e9duit \u00ab Clubcard Prices \u00bb, pr\u00e9sent\u00e9 ci-dessus.<\/p>\n<p>Lidl a accus\u00e9 Tesco de contrefaire son logo LIDL et sa marque sans mot en cherchant d\u00e9lib\u00e9r\u00e9ment \u00e0 profiter de la r\u00e9putation de Lidl en tant que supermarch\u00e9 \u00ab discount \u00bb connu pour la fourniture de valeur. Des demandes suppl\u00e9mentaires de concurrence d\u00e9loyale et de contrefa\u00e7on de droits d&#8217;auteur ont \u00e9galement \u00e9t\u00e9 introduites par Lidl. <\/p>\n<p>Le tribunal a estim\u00e9 que Tesco avait obtenu un avantage d\u00e9loyal en associant ses prix \u00e0 Lidl et \u00e0 sa r\u00e9putation de valeur \u00e0 bas prix. Il y avait \u00e9galement concurrence d\u00e9loyale et contrefa\u00e7on de droits d&#8217;auteur. La d\u00e9cision fait l&#8217;objet d&#8217;un appel et l&#8217;audience de trois jours s&#8217;est termin\u00e9e le 23<sup> <\/sup>f\u00e9vrier.  <\/p>\n<h5><strong>Le droit \u2013 pr\u00e9judice et avantage d\u00e9loyal<\/strong><\/h5>\n<p>Le <strong>pr\u00e9judice<\/strong> existe lorsque la capacit\u00e9 d&#8217;une marque \u00e0 identifier les biens ou services (pour lesquels elle est enregistr\u00e9e et utilis\u00e9e) comme provenant du propri\u00e9taire de cette marque est affaiblie. Cela peut \u00eatre d\u00fb au fait que l&#8217;utilisation de la marque ult\u00e9rieure rend difficile pour le public de s&#8217;appuyer sur son image de la marque ant\u00e9rieure pour identifier l&#8217;origine commerciale des biens ou services ou parce que l&#8217;utilisation de la marque ult\u00e9rieure influence n\u00e9gativement l&#8217;image de la marque ant\u00e9rieure. <\/p>\n<p>Il n&#8217;est pas essentiel que le propri\u00e9taire de la marque ult\u00e9rieure tire un avantage commercial r\u00e9el de son association avec la marque ant\u00e9rieure, mais bien que le risque de pr\u00e9judice puisse \u00eatre \u00e9tabli par d\u00e9duction, cela doit \u00eatre plus qu&#8217;une supposition. Par exemple, la n\u00e9cessit\u00e9 pour un propri\u00e9taire de prendre des \u00ab mesures d&#8217;\u00e9vitement \u00bb pour r\u00e9tablir ou amplifier le caract\u00e8re distinctif de sa marque afin d&#8217;\u00e9viter d&#8217;\u00eatre \u00e9vinc\u00e9 par l&#8217;utilisation de la marque ult\u00e9rieure peut d\u00e9noter un risque s\u00e9rieux de pr\u00e9judice. <\/p>\n<p>L&#8217;<strong>avantage d\u00e9loyal<\/strong> fait r\u00e9f\u00e9rence au concept juridique de l&#8217;avantage tir\u00e9 par la partie en raison de l&#8217;utilisation d&#8217;une marque ult\u00e9rieure identique ou similaire \u00e0 une marque jouissant d&#8217;une r\u00e9putation. Il couvre en particulier les cas o\u00f9, en raison du \u00ab transfert \u00bb et du parasitisme de l&#8217;image de la marque jouissant d&#8217;une r\u00e9putation vers la marque ult\u00e9rieure, la marque ult\u00e9rieure obtient un avantage quelconque. <\/p>\n<p>D\u00e9terminer s&#8217;il y a un avantage d\u00e9loyal n\u00e9cessite une \u00e9valuation globale de tous les facteurs pertinents dans les circonstances de l&#8217;affaire, y compris la force de la r\u00e9putation de la marque ant\u00e9rieure, le caract\u00e8re distinctif de la marque ant\u00e9rieure, le degr\u00e9 de similitude entre les marques et les biens ou services.<\/p>\n<p>Le droit n&#8217;est pas prescriptif quant \u00e0 ce qui peut constituer un \u00ab avantage \u00bb \u00ab d\u00e9loyal \u00bb, mais un avantage \u00e9conomique seul ne suffit pas. Il n&#8217;est pas non plus n\u00e9cessaire qu&#8217;une partie exploite intentionnellement la r\u00e9putation de la marque ant\u00e9rieure. <\/p>\n<p>Une conclusion de pr\u00e9judice et\/ou d&#8217;avantage d\u00e9loyal n\u00e9cessite qu&#8217;un changement dans le comportement \u00e9conomique des clients pour les biens ou services des d\u00e9fendeurs soit d\u00e9montr\u00e9. Mais des preuves r\u00e9elles d&#8217;un changement dans le comportement \u00e9conomique des consommateurs sont souvent difficiles \u00e0 obtenir, donc la probabilit\u00e9 d&#8217;un tel changement pourrait suffire. <\/p>\n<h5><strong>Les jugements \u2013 pr\u00e9judice et avantage d\u00e9loyal<\/strong><\/h5>\n<p>Le juge Smith dans <g id=\"gid_0\">Lidl c. Tesco<\/g> a consid\u00e9r\u00e9 qu&#8217;<strong>il y avait pr\u00e9judice et avantage d\u00e9loyal<\/strong> notamment parce que :  <\/p>\n<ul>\n<li>Lidl a d\u00fb prendre des mesures \u00ab correctives \u00bb en diffusant des publicit\u00e9s pour d\u00e9montrer les prix plus \u00e9lev\u00e9s des produits Tesco Clubcard par rapport \u00e0 ceux de Lidl<\/li>\n<li>l&#8217;effet objectif de la cr\u00e9ation du lien entre les marques signifiait que Tesco tirait un avantage d\u00e9loyal de la r\u00e9putation distinctive des marques de Lidl pour la valeur \u00e0 bas prix (r\u00e9duite) ;<\/li>\n<li>la marque de Tesco visait \u00e0 transmettre de la valeur, ce qui \u00e9tait plus facile et plus efficace en raison de la connexion avec les marques Lidl dont la r\u00e9putation \u00e9tait la valeur \u00e0 bas prix.<\/li>\n<\/ul>\n<p>Il y avait pr\u00e9judice et avantage d\u00e9loyal malgr\u00e9 le fait que Lidl acceptait qu&#8217;elle ne pouvait d\u00e9signer aucun individu sp\u00e9cifique qui avait reconnu un changement de comportement \u00e9conomique et malgr\u00e9 l&#8217;argument de Tesco qu&#8217;il n&#8217;y avait pas d&#8217;avantage d\u00e9loyal car si l&#8217;on achetait tous les produits couverts par la garantie Clubcard Prices, cela r\u00e9sulterait en une d\u00e9pense exactement similaire, ou inf\u00e9rieure, par rapport \u00e0 un achat \u00e9quivalent chez Lidl.<\/p>\n<p>Le juge Clarke dans <strong>Thatchers c. Aldi<\/strong> a consid\u00e9r\u00e9 qu&#8217;<strong>il n&#8217;y avait pas de pr\u00e9judice et d&#8217;avantage d\u00e9loyal<\/strong> malgr\u00e9 :<\/p>\n<ul>\n<li>avoir constat\u00e9 que la marque de Thatchers est similaire \u00e0 la marque d&#8217;Aldi ;<\/li>\n<li>la marque de Thatchers a une r\u00e9putation \u2013 il \u00e9tait convenu que la conception de l&#8217;emballage de Thatchers ajoutait \u00e0 l&#8217;attractivit\u00e9 du produit Thatchers et la pr\u00e9sence de citrons entiers attirait la client\u00e8le ;<\/li>\n<li>avoir trouv\u00e9 un lien entre les marques \u2013 Thatchers a produit des preuves de membres du public comparant le go\u00fbt des deux produits et des commentaires sur le produit Aldi \u00e9tant une \u00ab copie \u00bb ou une \u00ab imitation \u00bb du produit Thatchers.<\/li>\n<\/ul>\n<p>Mais finalement, cela n&#8217;\u00e9tait pas suffisant pour constater un changement dans le comportement \u00e9conomique du consommateur.<\/p>\n<h5><strong>Conclusions<\/strong><\/h5>\n<p>Il ne serait pas surprenant que Thatchers se sente quelque peu l\u00e9s\u00e9e par la d\u00e9cision.<\/p>\n<p>Bien que les noms de produits THATCHERS TAURUS \u00e9taient clairement dissemblables, les produits dans leur ensemble \u2013 avec les citrons entiers et le m\u00eame sch\u00e9ma de couleurs \u2013 \u00e9taient suffisamment similaires pour \u00eatre li\u00e9s dans l&#8217;esprit du public. Dans l&#8217;affaire Lidl, il y avait des preuves que la couleur bleue a longtemps \u00e9t\u00e9 associ\u00e9e \u00e0 Tesco, tandis que le jaune a \u00e9t\u00e9 reconnu comme ayant \u00ab le meilleur impact \u00bb pour le mat\u00e9riel de point de vente. Ainsi, dans les deux cas, les marques impliqu\u00e9es avaient des \u00ab faiblesses \u00bb qui n\u00e9anmoins n&#8217;ont pas nui \u00e0 une conclusion de similitude et de lien.  <\/p>\n<p>Sur le point du changement dans le comportement \u00e9conomique du consommateur, Lidl a franchi la ligne sur la base que la marque \u00ab Clubcard Prices \u00bb de Tesco visait <em>\u00ab \u00e0 transmettre de la valeur et ainsi \u00e0 influencer le comportement \u00e9conomique des acheteurs de supermarch\u00e9s \u00bb<\/em> nonobstant qu&#8217;il n&#8217;y avait pas d&#8217;intention sp\u00e9cifique de parasiter la r\u00e9putation de Lidl. Dans Thatchers, la possibilit\u00e9 que quelqu&#8217;un ach\u00e8te le produit Aldi au lieu du produit Thatchers, motiv\u00e9 par le lien et la diff\u00e9rence de prix entre les deux produits, n&#8217;a pas \u00e9t\u00e9 jug\u00e9e comme un risque suffisant pour le comportement \u00e9conomique du consommateur. <\/p>\n<p>Les conclusions du juge Clarke sur Thatchers peuvent avoir \u00e9t\u00e9 influenc\u00e9es par :<\/p>\n<ul>\n<li>le produit Aldi n&#8217;\u00e9tant plus sur le march\u00e9 ;<\/li>\n<li>la n\u00e9cessit\u00e9 qu&#8217;un avantage soit plus qu&#8217;un simple avantage \u00e9conomique ;<\/li>\n<li>l&#8217;improbabilit\u00e9 que le produit Aldi jette le produit Thatchers sous un jour n\u00e9gatif.<\/li>\n<\/ul>\n<p>C&#8217;est une d\u00e9cision finement \u00e9quilibr\u00e9e, mais j&#8217;ai le sentiment qu&#8217;un autre jour la d\u00e9cision aurait pu aller dans le sens de Thatchers et qu&#8217;elle a peut-\u00eatre \u00e9t\u00e9 tenue \u00e0 un standard plus strict que Lidl ; Aldi prendra la victoire pour l&#8217;instant \u2013<\/p>\n<p><em>\u00ab pas tout \u00e0 fait Thatchers Lemon mais pour la moiti\u00e9 du prix il n&#8217;y a pas grand-chose \u00e0 redire \u00bb<\/em>.<\/p>\n<p>Liens vers les jugements ci-dessous.<\/p>\n<p><a href=\"https:\/\/www.bailii.org\/ew\/cases\/EWHC\/Ch\/2023\/873.html\">Lidl c. Tesco<\/a><\/p>\n<p><a href=\"https:\/\/www.bailii.org\/ew\/cases\/EWHC\/IPEC\/2024\/88.html\">Thatchers c. Aldi<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<hr>\n<h5>Cet article a \u00e9t\u00e9 pr\u00e9par\u00e9 par le directeur des marques <a href=\"https:\/\/www.hgf.com\/fr\/our-people\/apostolos-dakanalis\/\">Apostolos Dakanalis<\/a><\/h5>\n","protected":false},"excerpt":{"rendered":"<p>Nous examinons l&#8217;avantage d\u00e9loyal et le pr\u00e9judice \u00e0 travers le prisme des r\u00e9cents jugements Lidl c. Tesco et Thatchers c. Aldi. Deux r\u00e9sultats tr\u00e8s diff\u00e9rents sur les m\u00eames principes juridiques &hellip;<\/p>\n","protected":false},"author":502,"featured_media":9004111222136960,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[536,517],"tags":[],"class_list":["post-9004111222136954","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articles","category-centre-de-connaissances","service-marques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>[in]\u00e9quitable \u2013 un regard sur les jugements Thatchers et Lidl - HGF<\/title>\n<meta name=\"description\" content=\"Nous examinons l&#039;avantage d\u00e9loyal et le pr\u00e9judice \u00e0 travers le prisme des r\u00e9cents jugements Lidl c. Tesco et Thatchers c. Aldi. Deux r\u00e9sultats tr\u00e8s diff\u00e9rents sur les m\u00eames principes juridiques et peut-\u00eatre un point de controverse en appel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[in]\u00e9quitable \u2013 un regard sur les jugements Thatchers et Lidl\" \/>\n<meta property=\"og:description\" content=\"Nous examinons l&#039;avantage d\u00e9loyal et le pr\u00e9judice \u00e0 travers le prisme des r\u00e9cents jugements Lidl c. Tesco et Thatchers c. Aldi. Deux r\u00e9sultats tr\u00e8s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/\" \/>\n<meta property=\"og:site_name\" content=\"HGF\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-12T13:33:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T20:08:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hgf.com\/wp-content\/uploads\/2024\/03\/svitlana-mnkU6aQowCE-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Georgia Melia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hgf_ip\" \/>\n<meta name=\"twitter:site\" content=\"@hgf_ip\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Georgia Melia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/articles\\\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/articles\\\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\\\/\"},\"author\":{\"name\":\"Georgia Melia\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#\\\/schema\\\/person\\\/7df0a22a79ff7cc91642cd3ce4882036\"},\"headline\":\"[in]\u00e9quitable \u2013 un regard sur les jugements Thatchers et Lidl\",\"datePublished\":\"2024-03-12T13:33:59+00:00\",\"dateModified\":\"2025-11-13T20:08:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/articles\\\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\\\/\"},\"wordCount\":1556,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/articles\\\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/svitlana-mnkU6aQowCE-unsplash-scaled.jpg\",\"articleSection\":[\"Articles\",\"Centre de connaissances\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/articles\\\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\\\/\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/articles\\\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\\\/\",\"name\":\"[in]\u00e9quitable \u2013 un regard sur les jugements Thatchers et Lidl - HGF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/articles\\\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/articles\\\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/svitlana-mnkU6aQowCE-unsplash-scaled.jpg\",\"datePublished\":\"2024-03-12T13:33:59+00:00\",\"dateModified\":\"2025-11-13T20:08:53+00:00\",\"description\":\"Nous examinons l'avantage d\u00e9loyal et le pr\u00e9judice \u00e0 travers le prisme des r\u00e9cents jugements Lidl c. Tesco et Thatchers c. Aldi. Deux r\u00e9sultats tr\u00e8s diff\u00e9rents sur les m\u00eames principes juridiques et peut-\u00eatre un point de controverse en appel.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/articles\\\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/centre-de-connaissances\\\/articles\\\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/svitlana-mnkU6aQowCE-unsplash-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/svitlana-mnkU6aQowCE-unsplash-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/\",\"name\":\"HGF\",\"description\":\"Intellectual Property Rights specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#organization\",\"name\":\"HGF\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hgf-logo-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hgf-logo-696x696-1.png\",\"width\":696,\"height\":696,\"caption\":\"HGF\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/hgf_ip\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hgf-limited-intellectual-property-specialists\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/fr\\\/#\\\/schema\\\/person\\\/7df0a22a79ff7cc91642cd3ce4882036\",\"name\":\"Georgia Melia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc759620959e751b0f1ac49d89cb60b8f62218f980cb9e4919ee6eb01c4fed6f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc759620959e751b0f1ac49d89cb60b8f62218f980cb9e4919ee6eb01c4fed6f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bc759620959e751b0f1ac49d89cb60b8f62218f980cb9e4919ee6eb01c4fed6f?s=96&d=mm&r=g\",\"caption\":\"Georgia Melia\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"[in]\u00e9quitable \u2013 un regard sur les jugements Thatchers et Lidl - HGF","description":"Nous examinons l'avantage d\u00e9loyal et le pr\u00e9judice \u00e0 travers le prisme des r\u00e9cents jugements Lidl c. Tesco et Thatchers c. Aldi. Deux r\u00e9sultats tr\u00e8s diff\u00e9rents sur les m\u00eames principes juridiques et peut-\u00eatre un point de controverse en appel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/","og_locale":"fr_FR","og_type":"article","og_title":"[in]\u00e9quitable \u2013 un regard sur les jugements Thatchers et Lidl","og_description":"Nous examinons l'avantage d\u00e9loyal et le pr\u00e9judice \u00e0 travers le prisme des r\u00e9cents jugements Lidl c. Tesco et Thatchers c. Aldi. Deux r\u00e9sultats tr\u00e8s","og_url":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/","og_site_name":"HGF","article_published_time":"2024-03-12T13:33:59+00:00","article_modified_time":"2025-11-13T20:08:53+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2024\/03\/svitlana-mnkU6aQowCE-unsplash-scaled.jpg","type":"image\/jpeg"}],"author":"Georgia Melia","twitter_card":"summary_large_image","twitter_creator":"@hgf_ip","twitter_site":"@hgf_ip","twitter_misc":{"\u00c9crit par":"Georgia Melia","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/#article","isPartOf":{"@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/"},"author":{"name":"Georgia Melia","@id":"https:\/\/www.hgf.com\/fr\/#\/schema\/person\/7df0a22a79ff7cc91642cd3ce4882036"},"headline":"[in]\u00e9quitable \u2013 un regard sur les jugements Thatchers et Lidl","datePublished":"2024-03-12T13:33:59+00:00","dateModified":"2025-11-13T20:08:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/"},"wordCount":1556,"publisher":{"@id":"https:\/\/www.hgf.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2024\/03\/svitlana-mnkU6aQowCE-unsplash-scaled.jpg","articleSection":["Articles","Centre de connaissances"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/","url":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/","name":"[in]\u00e9quitable \u2013 un regard sur les jugements Thatchers et Lidl - HGF","isPartOf":{"@id":"https:\/\/www.hgf.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/#primaryimage"},"image":{"@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2024\/03\/svitlana-mnkU6aQowCE-unsplash-scaled.jpg","datePublished":"2024-03-12T13:33:59+00:00","dateModified":"2025-11-13T20:08:53+00:00","description":"Nous examinons l'avantage d\u00e9loyal et le pr\u00e9judice \u00e0 travers le prisme des r\u00e9cents jugements Lidl c. Tesco et Thatchers c. Aldi. Deux r\u00e9sultats tr\u00e8s diff\u00e9rents sur les m\u00eames principes juridiques et peut-\u00eatre un point de controverse en appel.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hgf.com\/fr\/centre-de-connaissances\/articles\/inequitable-un-regard-sur-les-jugements-thatchers-et-lidl\/#primaryimage","url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2024\/03\/svitlana-mnkU6aQowCE-unsplash-scaled.jpg","contentUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2024\/03\/svitlana-mnkU6aQowCE-unsplash-scaled.jpg","width":2560,"height":1707},{"@type":"WebSite","@id":"https:\/\/www.hgf.com\/fr\/#website","url":"https:\/\/www.hgf.com\/fr\/","name":"HGF","description":"Intellectual Property Rights specialists","publisher":{"@id":"https:\/\/www.hgf.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hgf.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.hgf.com\/fr\/#organization","name":"HGF","url":"https:\/\/www.hgf.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.hgf.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/04\/hgf-logo-696x696-1.png","contentUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/04\/hgf-logo-696x696-1.png","width":696,"height":696,"caption":"HGF"},"image":{"@id":"https:\/\/www.hgf.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/hgf_ip","https:\/\/www.linkedin.com\/company\/hgf-limited-intellectual-property-specialists\/"]},{"@type":"Person","@id":"https:\/\/www.hgf.com\/fr\/#\/schema\/person\/7df0a22a79ff7cc91642cd3ce4882036","name":"Georgia Melia","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/bc759620959e751b0f1ac49d89cb60b8f62218f980cb9e4919ee6eb01c4fed6f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bc759620959e751b0f1ac49d89cb60b8f62218f980cb9e4919ee6eb01c4fed6f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bc759620959e751b0f1ac49d89cb60b8f62218f980cb9e4919ee6eb01c4fed6f?s=96&d=mm&r=g","caption":"Georgia Melia"}}]}},"_links":{"self":[{"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/posts\/9004111222136954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/users\/502"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/comments?post=9004111222136954"}],"version-history":[{"count":0,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/posts\/9004111222136954\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/media\/9004111222136960"}],"wp:attachment":[{"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/media?parent=9004111222136954"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/categories?post=9004111222136954"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hgf.com\/fr\/wp-json\/wp\/v2\/tags?post=9004111222136954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}