{"id":9004111222130379,"date":"2024-04-09T11:58:23","date_gmt":"2024-04-09T10:58:23","guid":{"rendered":"https:\/\/www.hgf.com\/?p=9004111222130379"},"modified":"2024-04-11T11:27:31","modified_gmt":"2024-04-11T10:27:31","slug":"dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven","status":"publish","type":"post","link":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/","title":{"rendered":"Dresden &#038; Salzburg Seminar: Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven"},"content":{"rendered":"<p class=\"p__large\">HGF freut sich, Sie zu unserem bevorstehenden Seminar zum Thema &#8220;Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven&#8221; in Salzburg und Dresden einzuladen. Das Seminar wird grundlegende Aspekte des Markenschutzes sowohl auf nationaler als auch auf europ\u00e4ischer Ebene behandeln.<\/p>\n<p><strong>Datum:<\/strong><\/p>\n<ul>\n<li>Salzburg: 14. Mai 2024, 17:30 Uhr<\/li>\n<li>Dresden: 11. Juni 2024, 18:00 Uhr<\/li>\n<\/ul>\n<p><strong>Ort:<\/strong><\/p>\n<ul>\n<li>Salzburg: HGF Europe LLP, <span class=\"LrzXr\">Rudolfskai 48, 5020 Salzburg<\/span><\/li>\n<li>Dresden: Impact Hub Gallery Dresden, <span class=\"LrzXr\">Trompeterstra\u00dfe 5, 01069 Dresden<\/span><\/li>\n<\/ul>\n<p>Im Rahmen unserer Seminarreihe in Dresden und Salzburg pr\u00e4sentieren wir ein spannendes Seminar, das sich mit den grundlegenden Fragen des Markenschutzes befasst. Egal, ob Sie bereits Erfahrung im Bereich des Markenrechts haben oder gerade erst anfangen, sich damit zu besch\u00e4ftigen, dieses Webinar bietet Ihnen wertvolle Einblicke und praxisnahe Tipps.<\/p>\n<p>Unsere erfahrene Rechtsanw\u00e4ltin <a href=\"https:\/\/www.hgf.com\/de\/unsere-mitarbeitenden\/julia-saladin\/\">Julia Saladin<\/a> wird grundlegende Aspekte des Markenschutzes sowohl auf nationaler als auch auf europ\u00e4ischer Ebene behandeln. Wir werden uns mit dem Weg einer Marke bis zur Erlangung des Markenschutzes, der rechtserhaltenden Benutzung der Marke, der Verteidigung einer Marke sowie mit grundlegenden \u00dcberlegungen zur Markenstrategie in Unternehmen auseinandersetzen.<\/p>\n<p>Das Seminar bietet nicht nur theoretisches Wissen, sondern auch praktische Einblicke und Fallbeispiele, die es Ihnen erm\u00f6glichen, das Gelernte in Ihrer beruflichen Praxis anzuwenden.<\/p>\n<p>Wir w\u00fcrden uns freuen, Sie beim Seminar begr\u00fc\u00dfen zu d\u00fcrfen, um Ihr Wissen \u00fcber Markenrecht und Markenschutz zu vertiefen und von den Erfahrungen unserer Expertin zu profitieren.<\/p>\n<p>Sie sind an dem Seminar interessiert, k\u00f6nnen aber nicht pers\u00f6nlich an einem der Termine teilnehmen? Schreiben Sie eine kurze E-Mail an Laura Schirlitzki (lschirlitzki@hgf.com).<\/p>\n<div class=\"btn-wrap btn-wrap--mb\"><a href=\"https:\/\/campaigns.hgf.com\/seminarreihe-salzburg-termin-5-markenschutz\/\" class=\"btn on-grey\" target=\"_blank\"><span>Hier f\u00fcr Salzburg anmelden<\/span><\/a><\/div>\n<div class=\"btn-wrap btn-wrap--mb\"><a href=\"https:\/\/campaigns.hgf.com\/seminarreihe-dresden-termin-5-markenschutz\/\" class=\"btn on-grey\" target=\"_blank\"><span>Hier f\u00fcr Dresden anmelden<\/span><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>HGF freut sich, Sie zu unserem bevorstehenden Seminar zum Thema &#8220;Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven&#8221; in Salzburg und Dresden einzuladen. Das Seminar wird grundlegende Aspekte des Markenschutzes sowohl &hellip;<\/p>\n","protected":false},"author":587,"featured_media":9004111222129451,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[526,525,518],"tags":[],"class_list":["post-9004111222130379","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hgf-veranstaltungen","category-veranstaltungen","category-wissens-hub","service-patente"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dresden &amp; Salzburg Seminar: Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven - HGF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dresden &amp; Salzburg Seminar: Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven\" \/>\n<meta property=\"og:description\" content=\"HGF freut sich, Sie zu unserem bevorstehenden Seminar zum Thema &quot;Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven&quot; in Salzburg und\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/\" \/>\n<meta property=\"og:site_name\" content=\"HGF\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-09T10:58:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-11T10:27:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/12\/Dresden-Image.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Laura Schirlitzki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hgf_ip\" \/>\n<meta name=\"twitter:site\" content=\"@hgf_ip\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura Schirlitzki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/veranstaltungen\\\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/veranstaltungen\\\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\\\/\"},\"author\":{\"name\":\"Laura Schirlitzki\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#\\\/schema\\\/person\\\/947e0bb489e71984ddee930860fabc85\"},\"headline\":\"Dresden &#038; Salzburg Seminar: Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven\",\"datePublished\":\"2024-04-09T10:58:23+00:00\",\"dateModified\":\"2024-04-11T10:27:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/veranstaltungen\\\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\\\/\"},\"wordCount\":311,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/veranstaltungen\\\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Dresden-Image.png\",\"articleSection\":[\"HGF-Veranstaltungen\",\"Veranstaltungen\",\"Wissens Hub\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/veranstaltungen\\\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\\\/\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/veranstaltungen\\\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\\\/\",\"name\":\"Dresden & Salzburg Seminar: Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven - HGF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/veranstaltungen\\\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/veranstaltungen\\\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Dresden-Image.png\",\"datePublished\":\"2024-04-09T10:58:23+00:00\",\"dateModified\":\"2024-04-11T10:27:31+00:00\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/veranstaltungen\\\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/veranstaltungen\\\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Dresden-Image.png\",\"contentUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Dresden-Image.png\",\"width\":800,\"height\":400},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/\",\"name\":\"HGF\",\"description\":\"Intellectual Property Rights specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#organization\",\"name\":\"HGF\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hgf-logo-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hgf-logo-696x696-1.png\",\"width\":696,\"height\":696,\"caption\":\"HGF\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/hgf_ip\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hgf-limited-intellectual-property-specialists\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#\\\/schema\\\/person\\\/947e0bb489e71984ddee930860fabc85\",\"name\":\"Laura Schirlitzki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d67b3a9d7c2be432ef98b37cecb1ee25228e9bed81175cafffa32eeabe6496eb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d67b3a9d7c2be432ef98b37cecb1ee25228e9bed81175cafffa32eeabe6496eb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d67b3a9d7c2be432ef98b37cecb1ee25228e9bed81175cafffa32eeabe6496eb?s=96&d=mm&r=g\",\"caption\":\"Laura Schirlitzki\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dresden & Salzburg Seminar: Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven - HGF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/","og_locale":"de_DE","og_type":"article","og_title":"Dresden & Salzburg Seminar: Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven","og_description":"HGF freut sich, Sie zu unserem bevorstehenden Seminar zum Thema \"Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven\" in Salzburg und","og_url":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/","og_site_name":"HGF","article_published_time":"2024-04-09T10:58:23+00:00","article_modified_time":"2024-04-11T10:27:31+00:00","og_image":[{"width":800,"height":400,"url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/12\/Dresden-Image.png","type":"image\/png"}],"author":"Laura Schirlitzki","twitter_card":"summary_large_image","twitter_creator":"@hgf_ip","twitter_site":"@hgf_ip","twitter_misc":{"Verfasst von":"Laura Schirlitzki","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/#article","isPartOf":{"@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/"},"author":{"name":"Laura Schirlitzki","@id":"https:\/\/www.hgf.com\/de\/#\/schema\/person\/947e0bb489e71984ddee930860fabc85"},"headline":"Dresden &#038; Salzburg Seminar: Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven","datePublished":"2024-04-09T10:58:23+00:00","dateModified":"2024-04-11T10:27:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/"},"wordCount":311,"publisher":{"@id":"https:\/\/www.hgf.com\/de\/#organization"},"image":{"@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/12\/Dresden-Image.png","articleSection":["HGF-Veranstaltungen","Veranstaltungen","Wissens Hub"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/","url":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/","name":"Dresden & Salzburg Seminar: Grundlagen des Markenschutzes: Nationale und europ\u00e4ische Perspektiven - HGF","isPartOf":{"@id":"https:\/\/www.hgf.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/#primaryimage"},"image":{"@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/12\/Dresden-Image.png","datePublished":"2024-04-09T10:58:23+00:00","dateModified":"2024-04-11T10:27:31+00:00","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/veranstaltungen\/dresden-salzburg-seminar-grundlagen-des-markenschutzes-nationale-und-europaeische-perspektiven\/#primaryimage","url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/12\/Dresden-Image.png","contentUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/12\/Dresden-Image.png","width":800,"height":400},{"@type":"WebSite","@id":"https:\/\/www.hgf.com\/de\/#website","url":"https:\/\/www.hgf.com\/de\/","name":"HGF","description":"Intellectual Property Rights specialists","publisher":{"@id":"https:\/\/www.hgf.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hgf.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.hgf.com\/de\/#organization","name":"HGF","url":"https:\/\/www.hgf.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.hgf.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/04\/hgf-logo-696x696-1.png","contentUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/04\/hgf-logo-696x696-1.png","width":696,"height":696,"caption":"HGF"},"image":{"@id":"https:\/\/www.hgf.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/hgf_ip","https:\/\/www.linkedin.com\/company\/hgf-limited-intellectual-property-specialists\/"]},{"@type":"Person","@id":"https:\/\/www.hgf.com\/de\/#\/schema\/person\/947e0bb489e71984ddee930860fabc85","name":"Laura Schirlitzki","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/d67b3a9d7c2be432ef98b37cecb1ee25228e9bed81175cafffa32eeabe6496eb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d67b3a9d7c2be432ef98b37cecb1ee25228e9bed81175cafffa32eeabe6496eb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d67b3a9d7c2be432ef98b37cecb1ee25228e9bed81175cafffa32eeabe6496eb?s=96&d=mm&r=g","caption":"Laura Schirlitzki"}}]}},"_links":{"self":[{"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/posts\/9004111222130379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/users\/587"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/comments?post=9004111222130379"}],"version-history":[{"count":0,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/posts\/9004111222130379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/media\/9004111222129451"}],"wp:attachment":[{"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/media?parent=9004111222130379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/categories?post=9004111222130379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/tags?post=9004111222130379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}