{"id":9004111222129289,"date":"2023-11-27T16:54:34","date_gmt":"2023-11-27T16:54:34","guid":{"rendered":"https:\/\/www.hgf.com\/?p=9004111222129289"},"modified":"2026-01-19T10:06:02","modified_gmt":"2026-01-19T10:06:02","slug":"pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson","status":"publish","type":"post","link":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/","title":{"rendered":"PRESSEMITTEILUNG &#8211; HGF ernennt neue Vorstandsvorsitzende: Ehemalige Leiterin der Abteilung Technik, Lucy Johnson"},"content":{"rendered":"<p>HGF hat eine neue Vorstandsvorsitzende, <a href=\"https:\/\/www.hgf.com\/de\/unsere-mitarbeitenden\/lucy-johnson\/\">Lucy Johnson<\/a>. Lucy war zuvor Leiterin der Engineering Group des Unternehmens. Mit sofortiger Wirkung tritt Lucy die Nachfolge von Jason Lumber an, der diese Position seit 2008 innehatte. Jason wird als gesch\u00e4tzter und engagierter Leiter der europ\u00e4ischen Markenrechtspraxis von HGF weiterarbeiten.<\/p>\n<p><em>Lucy Johnson, Vorsitzende, kommentiert: &#8220;Ich f\u00fchle mich sehr privilegiert, die Rolle in einer so aufregenden Zeit f\u00fcr die Kanzlei zu \u00fcbernehmen, in der wir uns in einer sich schnell ver\u00e4ndernden Landschaft bewegen, mit Ver\u00e4nderungen wie dem UP &amp; UPC sowie den Fortschritten bei der Nutzung von Technologie und dem hybriden Arbeiten. Wir haben eine ehrgeizige Strategie, die es uns erm\u00f6glichen soll, als starkes und nachhaltiges Unternehmen, in dem wir alle gerne arbeiten, weiter zu wachsen&#8221;.<\/em><\/p>\n<p>Lucy hat in den letzten 10 Jahren eine Karriere im Bereich F\u00fchrung aufgebaut und sich mit den Themen Teamentwicklung, Strategie, Mitarbeiterf\u00fchrung und Wandel besch\u00e4ftigt. Unter ihrer F\u00fchrung hat sich die Engineering Group zu einem erfolgreichen, wachsenden und kooperativen Team entwickelt.<\/p>\n<p><a href=\"https:\/\/www.hgf.com\/de\/unsere-mitarbeitenden\/martyn-fish\/\">Martyn Fish<\/a>, CEO, kommentiert: &#8220;Lucy verf\u00fcgt \u00fcber eine starke Kompetenz, die umfangreiche F\u00e4higkeiten in der Gewinnung von Mandanten und im Management mit Qualifikationen und Erfahrungen in den Bereichen F\u00fchrung, Management und Wandel verbindet. Das macht sie zu einer hervorragenden Wahl f\u00fcr den Vorsitz. Ich freue mich auf die Zusammenarbeit mit Lucy, wenn wir die Kanzlei gemeinsam auf dem Weg zu unserer Vision f\u00fchren, Europas Kanzlei f\u00fcr gewerblichen Rechtsschutz zu werden. Ich m\u00f6chte auch Jason f\u00fcr viele erfolgreiche Jahre als Vorsitzender danken&#8221;.<\/p>\n<p>In ihrer neuen Rolle als Vorsitzende wird sich Lucy weiterhin auf die Gewinnung und Verwaltung von Mandanten konzentrieren. Sie wird als Botschafterin f\u00fcr HGF fungieren und dabei helfen, den Ruf der Kanzlei weiter auszubauen, mit dem Ziel, neue Gesch\u00e4fte zu entwickeln und die besten zuk\u00fcnftigen Talente f\u00fcr die Kanzlei zu gewinnen. Lucy setzt sich leidenschaftlich f\u00fcr die Schaffung eines vielf\u00e4ltigen, gerechten und integrativen Unternehmens ein, in dem es f\u00fcr alle M\u00f6glichkeiten gibt, sich weiterzuentwickeln.<\/p>\n<p>Die Kanzlei hat au\u00dferdem <a href=\"https:\/\/www.hgf.com\/de\/unsere-mitarbeitenden\/hsu-min-chung\/\">Hsu Min Chung<\/a> und <a href=\"https:\/\/www.hgf.com\/de\/unsere-mitarbeitenden\/michael-nelson\/\">Mike Nelson<\/a> f\u00fcr eine Amtszeit von 3 Jahren in den Vorstand berufen.<\/p>\n<p>Diese Ernennung ist Teil eines strengen Auswahlprozesses f\u00fcr F\u00fchrungspositionen, das alle 3 Jahre stattfindet.<\/p>\n<p>&nbsp;<\/p>\n<h3>\u00dcber HGF:<\/h3>\n<p>HGF ist eine der gr\u00f6\u00dften Kanzleien f\u00fcr gewerblichen Rechtsschutz in Europa und hat die Vision, die f\u00fchrende Kanzlei f\u00fcr gewerblichen Rechtsschutz in Europa zu werden. Die Patentanw\u00e4lte, Rechtsanw\u00e4lte und in den L\u00e4ndern qualifizierten IP-Spezialisten der Kanzlei bieten eine integrierte L\u00f6sung f\u00fcr Mandanten. HGF erstellt und verwaltet IP-Portfolios f\u00fcr die weltweit f\u00fchrenden Unternehmen und Forschungsinstitute. Wir beraten Mandanten bei der Schaffung strategischer IP-Verm\u00f6genswerte auf der ganzen Welt und bieten erstklassiges Fachwissen in den Bereichen Einspruchs- &amp; Widerspruchsverfahren, Kommerzialisierung, Streitbeilegung und IP-Streitsachen zur Verteidigung und Durchsetzung von IP-Rechten.<\/p>\n<p>HGF wird regelm\u00e4\u00dfig mit Branchenpreisen ausgezeichnet und von den f\u00fchrenden juristischen Verzeichnissen anerkannt. HGF hat Niederlassungen in \u00d6sterreich, Frankreich, Deutschland, Irland, der Schweiz, den Niederlanden und Gro\u00dfbritannien.<\/p>\n<p>F\u00fcr weitere Informationen kontaktieren Sie bitte Nikki Butler unter +44 (0)113 233 0100 oder <a href=\"mailto:nbutler@hgf.com\">nbutler@hgf.com<\/a>. Weitere Informationen \u00fcber die Firma finden Sie unter <a href=\"https:\/\/www.hgf.com\/de\/\">www.hgf.com<\/a> oder schreiben Sie eine E-Mail an <a href=\"mailto:marketing@hgf.com\">marketing@hgf.com<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>HGF hat eine neue Vorstandsvorsitzende, Lucy Johnson. Lucy war zuvor Leiterin der Engineering Group des Unternehmens. Mit sofortiger Wirkung tritt Lucy die Nachfolge von Jason Lumber an, der diese Position &hellip;<\/p>\n","protected":false},"author":316,"featured_media":9004111222108937,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[531,518],"tags":[],"class_list":["post-9004111222129289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news-1","category-wissens-hub"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>PRESSEMITTEILUNG - HGF ernennt neue Vorstandsvorsitzende: Ehemalige Leiterin der Abteilung Technik, Lucy Johnson - HGF<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PRESSEMITTEILUNG - HGF ernennt neue Vorstandsvorsitzende: Ehemalige Leiterin der Abteilung Technik, Lucy Johnson\" \/>\n<meta property=\"og:description\" content=\"HGF hat eine neue Vorstandsvorsitzende, Lucy Johnson. Lucy war zuvor Leiterin der Engineering Group des Unternehmens. Mit sofortiger Wirkung tritt Lucy\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/\" \/>\n<meta property=\"og:site_name\" content=\"HGF\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-27T16:54:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-19T10:06:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.hgf.com\/wp-content\/uploads\/2020\/10\/Lucy-Johnson-new.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nichola Butler\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@hgf_ip\" \/>\n<meta name=\"twitter:site\" content=\"@hgf_ip\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nichola Butler\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/news-1\\\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/news-1\\\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\\\/\"},\"author\":{\"name\":\"Nichola Butler\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#\\\/schema\\\/person\\\/b8e8f97c9bef17c5a63b58710dec05fc\"},\"headline\":\"PRESSEMITTEILUNG &#8211; HGF ernennt neue Vorstandsvorsitzende: Ehemalige Leiterin der Abteilung Technik, Lucy Johnson\",\"datePublished\":\"2023-11-27T16:54:34+00:00\",\"dateModified\":\"2026-01-19T10:06:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/news-1\\\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\\\/\"},\"wordCount\":555,\"publisher\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/news-1\\\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Lucy-Johnson-new.jpg\",\"articleSection\":[\"Nachricht\",\"Wissens Hub\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/news-1\\\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\\\/\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/news-1\\\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\\\/\",\"name\":\"PRESSEMITTEILUNG - HGF ernennt neue Vorstandsvorsitzende: Ehemalige Leiterin der Abteilung Technik, Lucy Johnson - HGF\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/news-1\\\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/news-1\\\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Lucy-Johnson-new.jpg\",\"datePublished\":\"2023-11-27T16:54:34+00:00\",\"dateModified\":\"2026-01-19T10:06:02+00:00\",\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/news-1\\\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/wissens-hub\\\/news-1\\\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Lucy-Johnson-new.jpg\",\"contentUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2020\\\/10\\\/Lucy-Johnson-new.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/\",\"name\":\"HGF\",\"description\":\"Intellectual Property Rights specialists\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#organization\",\"name\":\"HGF\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hgf-logo-696x696-1.png\",\"contentUrl\":\"https:\\\/\\\/www.hgf.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/hgf-logo-696x696-1.png\",\"width\":696,\"height\":696,\"caption\":\"HGF\"},\"image\":{\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/hgf_ip\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/hgf-limited-intellectual-property-specialists\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.hgf.com\\\/de\\\/#\\\/schema\\\/person\\\/b8e8f97c9bef17c5a63b58710dec05fc\",\"name\":\"Nichola Butler\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g\",\"caption\":\"Nichola Butler\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PRESSEMITTEILUNG - HGF ernennt neue Vorstandsvorsitzende: Ehemalige Leiterin der Abteilung Technik, Lucy Johnson - HGF","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/","og_locale":"de_DE","og_type":"article","og_title":"PRESSEMITTEILUNG - HGF ernennt neue Vorstandsvorsitzende: Ehemalige Leiterin der Abteilung Technik, Lucy Johnson","og_description":"HGF hat eine neue Vorstandsvorsitzende, Lucy Johnson. Lucy war zuvor Leiterin der Engineering Group des Unternehmens. Mit sofortiger Wirkung tritt Lucy","og_url":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/","og_site_name":"HGF","article_published_time":"2023-11-27T16:54:34+00:00","article_modified_time":"2026-01-19T10:06:02+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2020\/10\/Lucy-Johnson-new.jpg","type":"image\/jpeg"}],"author":"Nichola Butler","twitter_card":"summary_large_image","twitter_creator":"@hgf_ip","twitter_site":"@hgf_ip","twitter_misc":{"Verfasst von":"Nichola Butler","Gesch\u00e4tzte Lesezeit":"3 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/#article","isPartOf":{"@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/"},"author":{"name":"Nichola Butler","@id":"https:\/\/www.hgf.com\/de\/#\/schema\/person\/b8e8f97c9bef17c5a63b58710dec05fc"},"headline":"PRESSEMITTEILUNG &#8211; HGF ernennt neue Vorstandsvorsitzende: Ehemalige Leiterin der Abteilung Technik, Lucy Johnson","datePublished":"2023-11-27T16:54:34+00:00","dateModified":"2026-01-19T10:06:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/"},"wordCount":555,"publisher":{"@id":"https:\/\/www.hgf.com\/de\/#organization"},"image":{"@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2020\/10\/Lucy-Johnson-new.jpg","articleSection":["Nachricht","Wissens Hub"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/","url":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/","name":"PRESSEMITTEILUNG - HGF ernennt neue Vorstandsvorsitzende: Ehemalige Leiterin der Abteilung Technik, Lucy Johnson - HGF","isPartOf":{"@id":"https:\/\/www.hgf.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/#primaryimage"},"image":{"@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/#primaryimage"},"thumbnailUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2020\/10\/Lucy-Johnson-new.jpg","datePublished":"2023-11-27T16:54:34+00:00","dateModified":"2026-01-19T10:06:02+00:00","inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.hgf.com\/de\/wissens-hub\/news-1\/pressemitteilung-hgf-ernennt-neue-vorstandsvorsitzende-ehemalige-leiterin-der-abteilung-technik-lucy-johnson\/#primaryimage","url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2020\/10\/Lucy-Johnson-new.jpg","contentUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2020\/10\/Lucy-Johnson-new.jpg","width":1920,"height":1080},{"@type":"WebSite","@id":"https:\/\/www.hgf.com\/de\/#website","url":"https:\/\/www.hgf.com\/de\/","name":"HGF","description":"Intellectual Property Rights specialists","publisher":{"@id":"https:\/\/www.hgf.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.hgf.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.hgf.com\/de\/#organization","name":"HGF","url":"https:\/\/www.hgf.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.hgf.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/04\/hgf-logo-696x696-1.png","contentUrl":"https:\/\/www.hgf.com\/wp-content\/uploads\/2023\/04\/hgf-logo-696x696-1.png","width":696,"height":696,"caption":"HGF"},"image":{"@id":"https:\/\/www.hgf.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/hgf_ip","https:\/\/www.linkedin.com\/company\/hgf-limited-intellectual-property-specialists\/"]},{"@type":"Person","@id":"https:\/\/www.hgf.com\/de\/#\/schema\/person\/b8e8f97c9bef17c5a63b58710dec05fc","name":"Nichola Butler","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/42cf846a377c3a78e27a6251ef72637db7331dd1905ba199ce32a5a55e286c39?s=96&d=mm&r=g","caption":"Nichola Butler"}}]}},"_links":{"self":[{"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/posts\/9004111222129289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/users\/316"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/comments?post=9004111222129289"}],"version-history":[{"count":0,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/posts\/9004111222129289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/media\/9004111222108937"}],"wp:attachment":[{"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/media?parent=9004111222129289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/categories?post=9004111222129289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hgf.com\/de\/wp-json\/wp\/v2\/tags?post=9004111222129289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}